{"id":26,"count":4,"description":"","link":"https:\/\/dev19.inserito.com\/hsea\/project-category\/green-energy\/","name":"Green Energy","slug":"green-energy","taxonomy":"project-category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/dev19.inserito.com\/hsea\/wp-json\/wp\/v2\/project-category\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev19.inserito.com\/hsea\/wp-json\/wp\/v2\/project-category"}],"about":[{"href":"https:\/\/dev19.inserito.com\/hsea\/wp-json\/wp\/v2\/taxonomies\/project-category"}]}}